{"id":249,"date":"2011-08-14T18:22:31","date_gmt":"2011-08-14T18:22:31","guid":{"rendered":"http:\/\/www.websitedesignwebsitedevelopment.com\/?p=249"},"modified":"2014-03-19T09:14:17","modified_gmt":"2014-03-19T09:14:17","slug":"class-returns-object","status":"publish","type":"post","link":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/","title":{"rendered":"$(&#8220;.class&#8221;) returns object"},"content":{"rendered":"<h2>jQuery $(&#8220;.class&#8221;) returns object<\/h2>\n<p>&lt;html&gt;<br \/>\n&lt;head&gt;<br \/>\n&lt;script type=&#8221;text\/javascript&#8221; src=&#8221;js\/jquery.js&#8221;&gt;&lt;\/script&gt;<br \/>\n&lt;script type=&#8221;text\/javascript&#8221;&gt;<br \/>\n$(document).ready(function(){<br \/>\n$(&#8220;label&#8221;).mousout(function(){<br \/>\n$(&#8220;.divClass&#8221;).hide();<br \/>\n});<br \/>\n});<br \/>\n&lt;\/script&gt;<br \/>\n&lt;\/head&gt;<br \/>\n&lt;body&gt;<\/p>\n<p>&lt;h3 class=&#8221;divClass&#8221;&gt;Hello world! text&lt;\/h3&gt;<br \/>\n&lt;p class=&#8221;divClass&#8221;&gt;Hello world paragraph text.&lt;\/p&gt;<br \/>\n&lt;p&gt;This is another paragraph.&lt;\/p&gt;<br \/>\n&lt;label&gt;Try to mouseover and then mouseout on here&lt;\/label&gt;<br \/>\n&lt;\/body&gt;<br \/>\n&lt;\/html&gt;<\/p>\n<p>Observed:<br \/>\nJQuery $(&#8220;.class&#8221;) returns object as we have<br \/>\nvar obj = document.getElementByClassName(&#8216;domObjClasses&#8217;);<\/p>\n<p>But this returns array.<\/p>\n<p>var obj = document.getElementById(&#8216;domObjId&#8217;);<\/p>\n<p>Here we will have an object by Id.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>jQuery $(&#8220;.class&#8221;) returns object &lt;html&gt; &lt;head&gt; &lt;script type=&#8221;text\/javascript&#8221; src=&#8221;js\/jquery.js&#8221;&gt;&lt;\/script&gt; &lt;script type=&#8221;text\/javascript&#8221;&gt; $(document).ready(function(){ $(&#8220;label&#8221;).mousout(function(){ $(&#8220;.divClass&#8221;).hide(); }); }); &lt;\/script&gt; &lt;\/head&gt; &lt;body&gt; &lt;h3 class=&#8221;divClass&#8221;&gt;Hello world! text&lt;\/h3&gt; &lt;p class=&#8221;divClass&#8221;&gt;Hello world paragraph text.&lt;\/p&gt; &lt;p&gt;This is another paragraph.&lt;\/p&gt; &lt;label&gt;Try to mouseover and then mouseout on here&lt;\/label&gt; &lt;\/body&gt; &lt;\/html&gt; Observed: JQuery $(&#8220;.class&#8221;) returns object as we have var obj = document.getElementByClassName(&#8216;domObjClasses&#8217;); But [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-249","post","type-post","status-publish","format-standard","hentry","category-website-development"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>$(&quot;.class&quot;) returns object<\/title>\n<meta name=\"description\" content=\"$(&quot;.class&quot;) returns object\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"$(&quot;.class&quot;) returns object\" \/>\n<meta property=\"og:description\" content=\"$(&quot;.class&quot;) returns object\" \/>\n<meta property=\"og:url\" content=\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/\" \/>\n<meta property=\"og:site_name\" content=\"AndroidBubble Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Website-Design-Website-Development\/172363336135453\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-14T18:22:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-19T09:14:17+00:00\" \/>\n<meta name=\"author\" content=\"Fahad\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fahad\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/\"},\"author\":{\"name\":\"Fahad\",\"@id\":\"https:\/\/androidbubble.com\/blog\/#\/schema\/person\/0a833b633f744c3a5e0de7c9a94e71f7\"},\"headline\":\"$(&#8220;.class&#8221;) returns object\",\"datePublished\":\"2011-08-14T18:22:31+00:00\",\"dateModified\":\"2014-03-19T09:14:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/\"},\"wordCount\":132,\"articleSection\":[\"Website Development\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/\",\"url\":\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/\",\"name\":\"$(\\\".class\\\") returns object\",\"isPartOf\":{\"@id\":\"https:\/\/androidbubble.com\/blog\/#website\"},\"datePublished\":\"2011-08-14T18:22:31+00:00\",\"dateModified\":\"2014-03-19T09:14:17+00:00\",\"author\":{\"@id\":\"https:\/\/androidbubble.com\/blog\/#\/schema\/person\/0a833b633f744c3a5e0de7c9a94e71f7\"},\"description\":\"$(\\\".class\\\") returns object\",\"breadcrumb\":{\"@id\":\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/androidbubble.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Website Development\",\"item\":\"https:\/\/androidbubble.com\/blog\/category\/website-development\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"$(&#8220;.class&#8221;) returns object\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/androidbubble.com\/blog\/#website\",\"url\":\"https:\/\/androidbubble.com\/blog\/\",\"name\":\"AndroidBubble Blog\",\"description\":\"Articles &amp; Posts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/androidbubble.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/androidbubble.com\/blog\/#\/schema\/person\/0a833b633f744c3a5e0de7c9a94e71f7\",\"name\":\"Fahad\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/androidbubble.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/afab5bcad71955d142a69df1758e6710aed4ab9cc2b5da28c54a7c3f39801b73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/afab5bcad71955d142a69df1758e6710aed4ab9cc2b5da28c54a7c3f39801b73?s=96&d=mm&r=g\",\"caption\":\"Fahad\"},\"sameAs\":[\"http:\/\/www.androidbubbles.com\/\",\"https:\/\/x.com\/phpFlex\"],\"url\":\"https:\/\/androidbubble.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"$(\".class\") returns object","description":"$(\".class\") returns object","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/","og_locale":"en_US","og_type":"article","og_title":"$(\".class\") returns object","og_description":"$(\".class\") returns object","og_url":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/","og_site_name":"AndroidBubble Blog","article_publisher":"https:\/\/www.facebook.com\/pages\/Website-Design-Website-Development\/172363336135453","article_published_time":"2011-08-14T18:22:31+00:00","article_modified_time":"2014-03-19T09:14:17+00:00","author":"Fahad","twitter_misc":{"Written by":"Fahad","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/#article","isPartOf":{"@id":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/"},"author":{"name":"Fahad","@id":"https:\/\/androidbubble.com\/blog\/#\/schema\/person\/0a833b633f744c3a5e0de7c9a94e71f7"},"headline":"$(&#8220;.class&#8221;) returns object","datePublished":"2011-08-14T18:22:31+00:00","dateModified":"2014-03-19T09:14:17+00:00","mainEntityOfPage":{"@id":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/"},"wordCount":132,"articleSection":["Website Development"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/","url":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/","name":"$(\".class\") returns object","isPartOf":{"@id":"https:\/\/androidbubble.com\/blog\/#website"},"datePublished":"2011-08-14T18:22:31+00:00","dateModified":"2014-03-19T09:14:17+00:00","author":{"@id":"https:\/\/androidbubble.com\/blog\/#\/schema\/person\/0a833b633f744c3a5e0de7c9a94e71f7"},"description":"$(\".class\") returns object","breadcrumb":{"@id":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/androidbubble.com\/blog\/website-development\/class-returns-object\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/androidbubble.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Website Development","item":"https:\/\/androidbubble.com\/blog\/category\/website-development\/"},{"@type":"ListItem","position":3,"name":"$(&#8220;.class&#8221;) returns object"}]},{"@type":"WebSite","@id":"https:\/\/androidbubble.com\/blog\/#website","url":"https:\/\/androidbubble.com\/blog\/","name":"AndroidBubble Blog","description":"Articles &amp; Posts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/androidbubble.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/androidbubble.com\/blog\/#\/schema\/person\/0a833b633f744c3a5e0de7c9a94e71f7","name":"Fahad","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/androidbubble.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/afab5bcad71955d142a69df1758e6710aed4ab9cc2b5da28c54a7c3f39801b73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afab5bcad71955d142a69df1758e6710aed4ab9cc2b5da28c54a7c3f39801b73?s=96&d=mm&r=g","caption":"Fahad"},"sameAs":["http:\/\/www.androidbubbles.com\/","https:\/\/x.com\/phpFlex"],"url":"https:\/\/androidbubble.com\/blog\/author\/admin\/"}]}},"views":401,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/posts\/249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/comments?post=249"}],"version-history":[{"count":2,"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/posts\/249\/revisions"}],"predecessor-version":[{"id":278,"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/posts\/249\/revisions\/278"}],"wp:attachment":[{"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/media?parent=249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/categories?post=249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/androidbubble.com\/blog\/wp-json\/wp\/v2\/tags?post=249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}